{"id":13341,"date":"2016-02-17T00:00:00","date_gmt":"2016-02-16T23:00:00","guid":{"rendered":"https:\/\/www.banfi.it\/uncategorized\/castello-banfi-il-borgo-e-tra-i-castelli-piu-belli-in-toscana-in-un-servizio-uscito-su-la-nazione-dedicato-alle-realta-ricettive-nel-cuore-della-toscana\/"},"modified":"2024-11-04T18:02:35","modified_gmt":"2024-11-04T17:02:35","slug":"castello-banfi-the-borgo-is-among-the-most-beautiful-castles-in-tuscany-in-a-report-published-in-la-nazione-dedicated-to-accommodation-in-the-heart-of-tuscany","status":"publish","type":"post","link":"https:\/\/www.banfi.it\/eng\/castello-banfi-il-borgo-e-tra-i-castelli-piu-belli-in-toscana-in-un-servizio-uscito-su-la-nazione-dedicato-alle-realta-ricettive-nel-cuore-della-toscana\/","title":{"rendered":"Castello Banfi - The Borgo is among the most beautiful castles in Tuscany, in a report published in La Nazione dedicated to accommodation in the heart of Tuscany"},"content":{"rendered":"<p><a href=\"https:\/\/www.banfi.it\/eng\/hospitality\/\">Banfi Castle - The Village<\/a> is among the most beautiful castles in Tuscany, in a report published in <a href=\"https:\/\/www.lanazione.it\/\" target=\"_blank\" rel=\"noopener\">The Nation<\/a> dedicated to accommodation in the heart of Tuscany.<\/p>","protected":false},"excerpt":{"rendered":"<p>Castello Banfi - The Borgo is among the most beautiful castles in Tuscany, in an article published in La Nazione dedicated to accommodation in the heart of Tuscany.<\/p>","protected":false},"author":10,"featured_media":16012,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[12],"tags":[],"class_list":["post-13341","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Castelli pi\u00f9 belli in Toscana - Banfi<\/title>\n<meta name=\"description\" content=\"Castello Banfi - Il Borgo \u00e9 tra i castelli pi\u00f9 belli in Toscana. Parola de La Nazione in un servizio sulle realt\u00e0 ricettive della regione.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.banfi.it\/eng\/castello-banfi-the-borgo-is-among-the-most-beautiful-castles-in-tuscany-in-a-report-published-in-la-nazione-dedicated-to-accommodation-in-the-heart-of-tuscany\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Castelli pi\u00f9 belli in Toscana - Banfi\" \/>\n<meta property=\"og:description\" content=\"Castello Banfi - Il Borgo \u00e9 tra i castelli pi\u00f9 belli in Toscana. Parola de La Nazione in un servizio sulle realt\u00e0 ricettive della regione.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.banfi.it\/eng\/castello-banfi-the-borgo-is-among-the-most-beautiful-castles-in-tuscany-in-a-report-published-in-la-nazione-dedicated-to-accommodation-in-the-heart-of-tuscany\/\" \/>\n<meta property=\"og:site_name\" content=\"Banfi\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/BanfiOfficial\" \/>\n<meta property=\"article:published_time\" content=\"2016-02-16T23:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-11-04T17:02:35+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.banfi.it\/wp-content\/uploads\/2016\/02\/banfi-castello-borghi-piu-belli-tuscany-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1707\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Banfi Banfi\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@BanfiOfficial\" \/>\n<meta name=\"twitter:site\" content=\"@BanfiOfficial\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Banfi Banfi\" \/>\n\t<meta name=\"twitter:label2\" content=\"Estimated reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.banfi.it\\\/castello-banfi-il-borgo-e-tra-i-castelli-piu-belli-in-toscana-in-un-servizio-uscito-su-la-nazione-dedicato-alle-realta-ricettive-nel-cuore-della-toscana\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.banfi.it\\\/castello-banfi-il-borgo-e-tra-i-castelli-piu-belli-in-toscana-in-un-servizio-uscito-su-la-nazione-dedicato-alle-realta-ricettive-nel-cuore-della-toscana\\\/\"},\"author\":{\"name\":\"Banfi Banfi\",\"@id\":\"https:\\\/\\\/www.banfi.it\\\/#\\\/schema\\\/person\\\/8a6a445b348dc073b2dee2e5ba75d2fa\"},\"headline\":\"Castello Banfi &#8211; Il Borgo \u00e9 tra i castelli pi\u00f9 belli in Toscana, in un servizio uscito su La Nazione dedicato alle realt\u00e0 ricettive nel cuore della Toscana\",\"datePublished\":\"2016-02-16T23:00:00+00:00\",\"dateModified\":\"2024-11-04T17:02:35+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.banfi.it\\\/castello-banfi-il-borgo-e-tra-i-castelli-piu-belli-in-toscana-in-un-servizio-uscito-su-la-nazione-dedicato-alle-realta-ricettive-nel-cuore-della-toscana\\\/\"},\"wordCount\":54,\"publisher\":{\"@id\":\"https:\\\/\\\/www.banfi.it\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.banfi.it\\\/castello-banfi-il-borgo-e-tra-i-castelli-piu-belli-in-toscana-in-un-servizio-uscito-su-la-nazione-dedicato-alle-realta-ricettive-nel-cuore-della-toscana\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.banfi.it\\\/wp-content\\\/uploads\\\/2016\\\/02\\\/banfi-castello-borghi-piu-belli-tuscany-scaled.jpg\",\"articleSection\":[\"News\"],\"inLanguage\":\"en-GB\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.banfi.it\\\/castello-banfi-il-borgo-e-tra-i-castelli-piu-belli-in-toscana-in-un-servizio-uscito-su-la-nazione-dedicato-alle-realta-ricettive-nel-cuore-della-toscana\\\/\",\"url\":\"https:\\\/\\\/www.banfi.it\\\/castello-banfi-il-borgo-e-tra-i-castelli-piu-belli-in-toscana-in-un-servizio-uscito-su-la-nazione-dedicato-alle-realta-ricettive-nel-cuore-della-toscana\\\/\",\"name\":\"Castelli pi\u00f9 belli in Toscana - Banfi\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.banfi.it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.banfi.it\\\/castello-banfi-il-borgo-e-tra-i-castelli-piu-belli-in-toscana-in-un-servizio-uscito-su-la-nazione-dedicato-alle-realta-ricettive-nel-cuore-della-toscana\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.banfi.it\\\/castello-banfi-il-borgo-e-tra-i-castelli-piu-belli-in-toscana-in-un-servizio-uscito-su-la-nazione-dedicato-alle-realta-ricettive-nel-cuore-della-toscana\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.banfi.it\\\/wp-content\\\/uploads\\\/2016\\\/02\\\/banfi-castello-borghi-piu-belli-tuscany-scaled.jpg\",\"datePublished\":\"2016-02-16T23:00:00+00:00\",\"dateModified\":\"2024-11-04T17:02:35+00:00\",\"description\":\"Castello Banfi - Il Borgo \u00e9 tra i castelli pi\u00f9 belli in Toscana. Parola de La Nazione in un servizio sulle realt\u00e0 ricettive della regione.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.banfi.it\\\/castello-banfi-il-borgo-e-tra-i-castelli-piu-belli-in-toscana-in-un-servizio-uscito-su-la-nazione-dedicato-alle-realta-ricettive-nel-cuore-della-toscana\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.banfi.it\\\/castello-banfi-il-borgo-e-tra-i-castelli-piu-belli-in-toscana-in-un-servizio-uscito-su-la-nazione-dedicato-alle-realta-ricettive-nel-cuore-della-toscana\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/www.banfi.it\\\/castello-banfi-il-borgo-e-tra-i-castelli-piu-belli-in-toscana-in-un-servizio-uscito-su-la-nazione-dedicato-alle-realta-ricettive-nel-cuore-della-toscana\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.banfi.it\\\/wp-content\\\/uploads\\\/2016\\\/02\\\/banfi-castello-borghi-piu-belli-tuscany-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/www.banfi.it\\\/wp-content\\\/uploads\\\/2016\\\/02\\\/banfi-castello-borghi-piu-belli-tuscany-scaled.jpg\",\"width\":2560,\"height\":1707},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.banfi.it\\\/castello-banfi-il-borgo-e-tra-i-castelli-piu-belli-in-toscana-in-un-servizio-uscito-su-la-nazione-dedicato-alle-realta-ricettive-nel-cuore-della-toscana\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.banfi.it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"News\",\"item\":\"https:\\\/\\\/www.banfi.it\\\/category\\\/news\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Castello Banfi &#8211; Il Borgo \u00e9 tra i castelli pi\u00f9 belli in Toscana, in un servizio uscito su La Nazione dedicato alle realt\u00e0 ricettive nel cuore della Toscana\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.banfi.it\\\/#website\",\"url\":\"https:\\\/\\\/www.banfi.it\\\/\",\"name\":\"Banfi\",\"description\":\"For a better wine world\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.banfi.it\\\/#organization\"},\"alternateName\":\"Banfi\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.banfi.it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.banfi.it\\\/#organization\",\"name\":\"Banfi\",\"alternateName\":\"Banfi\",\"url\":\"https:\\\/\\\/www.banfi.it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/www.banfi.it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.banfi.it\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/Logo-stemma-banfi-scuro_a.png\",\"contentUrl\":\"https:\\\/\\\/www.banfi.it\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/Logo-stemma-banfi-scuro_a.png\",\"width\":186,\"height\":173,\"caption\":\"Banfi\"},\"image\":{\"@id\":\"https:\\\/\\\/www.banfi.it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/BanfiOfficial\",\"https:\\\/\\\/x.com\\\/BanfiOfficial\",\"https:\\\/\\\/www.instagram.com\\\/banfiofficial\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/banfiofficial\\\/\",\"https:\\\/\\\/www.youtube.com\\\/c\\\/Castellobanfi\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.banfi.it\\\/#\\\/schema\\\/person\\\/8a6a445b348dc073b2dee2e5ba75d2fa\",\"name\":\"Banfi Banfi\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0eeada89b82f4c563f9dc31d28d5b2ea9a9aaa487aaa4d39442ced8f921c6402?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0eeada89b82f4c563f9dc31d28d5b2ea9a9aaa487aaa4d39442ced8f921c6402?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0eeada89b82f4c563f9dc31d28d5b2ea9a9aaa487aaa4d39442ced8f921c6402?s=96&d=mm&r=g\",\"caption\":\"Banfi Banfi\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Most beautiful castles in Tuscany - Banfi","description":"Castello Banfi - The Borgo is among the most beautiful castles in Tuscany. Word from La Nazione in a report on the region's accommodation facilities.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.banfi.it\/eng\/castello-banfi-the-borgo-is-among-the-most-beautiful-castles-in-tuscany-in-a-report-published-in-la-nazione-dedicated-to-accommodation-in-the-heart-of-tuscany\/","og_locale":"en_GB","og_type":"article","og_title":"Castelli pi\u00f9 belli in Toscana - Banfi","og_description":"Castello Banfi - Il Borgo \u00e9 tra i castelli pi\u00f9 belli in Toscana. Parola de La Nazione in un servizio sulle realt\u00e0 ricettive della regione.","og_url":"https:\/\/www.banfi.it\/eng\/castello-banfi-the-borgo-is-among-the-most-beautiful-castles-in-tuscany-in-a-report-published-in-la-nazione-dedicated-to-accommodation-in-the-heart-of-tuscany\/","og_site_name":"Banfi","article_publisher":"https:\/\/www.facebook.com\/BanfiOfficial","article_published_time":"2016-02-16T23:00:00+00:00","article_modified_time":"2024-11-04T17:02:35+00:00","og_image":[{"width":2560,"height":1707,"url":"https:\/\/www.banfi.it\/wp-content\/uploads\/2016\/02\/banfi-castello-borghi-piu-belli-tuscany-scaled.jpg","type":"image\/jpeg"}],"author":"Banfi Banfi","twitter_card":"summary_large_image","twitter_creator":"@BanfiOfficial","twitter_site":"@BanfiOfficial","twitter_misc":{"Written by":"Banfi Banfi","Estimated reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.banfi.it\/castello-banfi-il-borgo-e-tra-i-castelli-piu-belli-in-toscana-in-un-servizio-uscito-su-la-nazione-dedicato-alle-realta-ricettive-nel-cuore-della-toscana\/#article","isPartOf":{"@id":"https:\/\/www.banfi.it\/castello-banfi-il-borgo-e-tra-i-castelli-piu-belli-in-toscana-in-un-servizio-uscito-su-la-nazione-dedicato-alle-realta-ricettive-nel-cuore-della-toscana\/"},"author":{"name":"Banfi Banfi","@id":"https:\/\/www.banfi.it\/#\/schema\/person\/8a6a445b348dc073b2dee2e5ba75d2fa"},"headline":"Castello Banfi &#8211; Il Borgo \u00e9 tra i castelli pi\u00f9 belli in Toscana, in un servizio uscito su La Nazione dedicato alle realt\u00e0 ricettive nel cuore della Toscana","datePublished":"2016-02-16T23:00:00+00:00","dateModified":"2024-11-04T17:02:35+00:00","mainEntityOfPage":{"@id":"https:\/\/www.banfi.it\/castello-banfi-il-borgo-e-tra-i-castelli-piu-belli-in-toscana-in-un-servizio-uscito-su-la-nazione-dedicato-alle-realta-ricettive-nel-cuore-della-toscana\/"},"wordCount":54,"publisher":{"@id":"https:\/\/www.banfi.it\/#organization"},"image":{"@id":"https:\/\/www.banfi.it\/castello-banfi-il-borgo-e-tra-i-castelli-piu-belli-in-toscana-in-un-servizio-uscito-su-la-nazione-dedicato-alle-realta-ricettive-nel-cuore-della-toscana\/#primaryimage"},"thumbnailUrl":"https:\/\/www.banfi.it\/wp-content\/uploads\/2016\/02\/banfi-castello-borghi-piu-belli-tuscany-scaled.jpg","articleSection":["News"],"inLanguage":"en-GB"},{"@type":"WebPage","@id":"https:\/\/www.banfi.it\/castello-banfi-il-borgo-e-tra-i-castelli-piu-belli-in-toscana-in-un-servizio-uscito-su-la-nazione-dedicato-alle-realta-ricettive-nel-cuore-della-toscana\/","url":"https:\/\/www.banfi.it\/castello-banfi-il-borgo-e-tra-i-castelli-piu-belli-in-toscana-in-un-servizio-uscito-su-la-nazione-dedicato-alle-realta-ricettive-nel-cuore-della-toscana\/","name":"Most beautiful castles in Tuscany - Banfi","isPartOf":{"@id":"https:\/\/www.banfi.it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.banfi.it\/castello-banfi-il-borgo-e-tra-i-castelli-piu-belli-in-toscana-in-un-servizio-uscito-su-la-nazione-dedicato-alle-realta-ricettive-nel-cuore-della-toscana\/#primaryimage"},"image":{"@id":"https:\/\/www.banfi.it\/castello-banfi-il-borgo-e-tra-i-castelli-piu-belli-in-toscana-in-un-servizio-uscito-su-la-nazione-dedicato-alle-realta-ricettive-nel-cuore-della-toscana\/#primaryimage"},"thumbnailUrl":"https:\/\/www.banfi.it\/wp-content\/uploads\/2016\/02\/banfi-castello-borghi-piu-belli-tuscany-scaled.jpg","datePublished":"2016-02-16T23:00:00+00:00","dateModified":"2024-11-04T17:02:35+00:00","description":"Castello Banfi - The Borgo is among the most beautiful castles in Tuscany. Word from La Nazione in a report on the region's accommodation facilities.","breadcrumb":{"@id":"https:\/\/www.banfi.it\/castello-banfi-il-borgo-e-tra-i-castelli-piu-belli-in-toscana-in-un-servizio-uscito-su-la-nazione-dedicato-alle-realta-ricettive-nel-cuore-della-toscana\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.banfi.it\/castello-banfi-il-borgo-e-tra-i-castelli-piu-belli-in-toscana-in-un-servizio-uscito-su-la-nazione-dedicato-alle-realta-ricettive-nel-cuore-della-toscana\/"]}]},{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/www.banfi.it\/castello-banfi-il-borgo-e-tra-i-castelli-piu-belli-in-toscana-in-un-servizio-uscito-su-la-nazione-dedicato-alle-realta-ricettive-nel-cuore-della-toscana\/#primaryimage","url":"https:\/\/www.banfi.it\/wp-content\/uploads\/2016\/02\/banfi-castello-borghi-piu-belli-tuscany-scaled.jpg","contentUrl":"https:\/\/www.banfi.it\/wp-content\/uploads\/2016\/02\/banfi-castello-borghi-piu-belli-tuscany-scaled.jpg","width":2560,"height":1707},{"@type":"BreadcrumbList","@id":"https:\/\/www.banfi.it\/castello-banfi-il-borgo-e-tra-i-castelli-piu-belli-in-toscana-in-un-servizio-uscito-su-la-nazione-dedicato-alle-realta-ricettive-nel-cuore-della-toscana\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.banfi.it\/"},{"@type":"ListItem","position":2,"name":"News","item":"https:\/\/www.banfi.it\/category\/news\/"},{"@type":"ListItem","position":3,"name":"Castello Banfi &#8211; Il Borgo \u00e9 tra i castelli pi\u00f9 belli in Toscana, in un servizio uscito su La Nazione dedicato alle realt\u00e0 ricettive nel cuore della Toscana"}]},{"@type":"WebSite","@id":"https:\/\/www.banfi.it\/#website","url":"https:\/\/www.banfi.it\/","name":"Banfi","description":"For a better wine world","publisher":{"@id":"https:\/\/www.banfi.it\/#organization"},"alternateName":"Banfi","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.banfi.it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/www.banfi.it\/#organization","name":"Banfi","alternateName":"Banfi","url":"https:\/\/www.banfi.it\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/www.banfi.it\/#\/schema\/logo\/image\/","url":"https:\/\/www.banfi.it\/wp-content\/uploads\/2024\/06\/Logo-stemma-banfi-scuro_a.png","contentUrl":"https:\/\/www.banfi.it\/wp-content\/uploads\/2024\/06\/Logo-stemma-banfi-scuro_a.png","width":186,"height":173,"caption":"Banfi"},"image":{"@id":"https:\/\/www.banfi.it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/BanfiOfficial","https:\/\/x.com\/BanfiOfficial","https:\/\/www.instagram.com\/banfiofficial\/","https:\/\/www.linkedin.com\/company\/banfiofficial\/","https:\/\/www.youtube.com\/c\/Castellobanfi"]},{"@type":"Person","@id":"https:\/\/www.banfi.it\/#\/schema\/person\/8a6a445b348dc073b2dee2e5ba75d2fa","name":"Banfi Banfi","image":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/secure.gravatar.com\/avatar\/0eeada89b82f4c563f9dc31d28d5b2ea9a9aaa487aaa4d39442ced8f921c6402?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/0eeada89b82f4c563f9dc31d28d5b2ea9a9aaa487aaa4d39442ced8f921c6402?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/0eeada89b82f4c563f9dc31d28d5b2ea9a9aaa487aaa4d39442ced8f921c6402?s=96&d=mm&r=g","caption":"Banfi Banfi"}}]}},"_links":{"self":[{"href":"https:\/\/www.banfi.it\/eng\/wp-json\/wp\/v2\/posts\/13341","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.banfi.it\/eng\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.banfi.it\/eng\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.banfi.it\/eng\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/www.banfi.it\/eng\/wp-json\/wp\/v2\/comments?post=13341"}],"version-history":[{"count":0,"href":"https:\/\/www.banfi.it\/eng\/wp-json\/wp\/v2\/posts\/13341\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.banfi.it\/eng\/wp-json\/wp\/v2\/media\/16012"}],"wp:attachment":[{"href":"https:\/\/www.banfi.it\/eng\/wp-json\/wp\/v2\/media?parent=13341"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.banfi.it\/eng\/wp-json\/wp\/v2\/categories?post=13341"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.banfi.it\/eng\/wp-json\/wp\/v2\/tags?post=13341"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}