{"id":13228,"date":"2010-09-02T00:00:00","date_gmt":"2010-09-01T22:00:00","guid":{"rendered":"https:\/\/www.banfi.it\/uncategorized\/castello-banfi-sul-numero-di-settembre-di-traveller-conde-nast-edizione-italiana\/"},"modified":"2024-10-21T17:56:04","modified_gmt":"2024-10-21T15:56:04","slug":"castello-banfi-in-the-september-issue-of-traveller-conde-nast-italian-edition","status":"publish","type":"post","link":"https:\/\/www.banfi.it\/eng\/castello-banfi-sul-numero-di-settembre-di-traveller-conde-nast-edizione-italiana\/","title":{"rendered":"Castello Banfi in the September issue of Traveller, Cond\u00e9 Nast, Italian edition"},"content":{"rendered":"<p>Castello Banfi is featured in the September issue of the Italian edition of <a href=\"https:\/\/www.cntraveller.com\/\" target=\"_blank\" rel=\"noopener\">Traveller<\/a>the Cond\u00e9 Nast Group's famous travel magazine.<\/p>\n<h2>Castello Banfi in the September issue of Traveller, Cond\u00e9 Nast, Italian edition<\/h2>\n<p>Once again, the renowned Montalcino estate, world-famous for its wines and in particular for the <a href=\"https:\/\/www.banfi.it\/eng\/products\/poggio-alle-mura\/\">Brunello di Montalcino<\/a>, is mentioned as one of the most exclusive wineries, where you can fully savour the magical atmosphere of the grape harvest and enjoy the serenity of the Tuscan countryside, staying at the exclusive <a href=\"https:\/\/www.banfi.it\/eng\/hospitality\/\">resort The Borgo di Castello Banfi<\/a>.<\/p>","protected":false},"excerpt":{"rendered":"<p>Castello Banfi \u00e8 presente sul numero di settembre dell\u2019edizione italiana di Traveller, la famosa rivista del gruppo Cond\u00e9 Nast dedicata ai viaggi. Castello Banfi sul numero di settembre di Traveller, Cond\u00e9 Nast, edizione italiana Ancora una volta, la rinomata tenuta montalcinese, famosa in tutto il mondo per i suoi vini ed in particolare per il [&hellip;]<\/p>\n","protected":false},"author":10,"featured_media":16310,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[12],"tags":[],"class_list":["post-13228","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Castello Banfi sul numero di settembre di Traveller, Cond\u00e9 Nast, edizione italiana<\/title>\n<meta name=\"description\" content=\"Castello Banfi sul numero di settembre di Traveller, Cond\u00e9 Nast, edizione italiana. Scopri di pi\u00f9 nell&#039;articolo!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.banfi.it\/eng\/castello-banfi-in-the-september-issue-of-traveller-conde-nast-italian-edition\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Castello Banfi sul numero di settembre di Traveller, Cond\u00e9 Nast, edizione italiana\" \/>\n<meta property=\"og:description\" content=\"Castello Banfi sul numero di settembre di Traveller, Cond\u00e9 Nast, edizione italiana. Scopri di pi\u00f9 nell&#039;articolo!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.banfi.it\/eng\/castello-banfi-in-the-september-issue-of-traveller-conde-nast-italian-edition\/\" \/>\n<meta property=\"og:site_name\" content=\"Banfi\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/BanfiOfficial\" \/>\n<meta property=\"article:published_time\" content=\"2010-09-01T22:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-10-21T15:56:04+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.banfi.it\/wp-content\/uploads\/2010\/09\/banfi-castello-conde-nast-traveller-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1707\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Banfi Banfi\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@BanfiOfficial\" \/>\n<meta name=\"twitter:site\" content=\"@BanfiOfficial\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Banfi Banfi\" \/>\n\t<meta name=\"twitter:label2\" content=\"Estimated reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.banfi.it\\\/castello-banfi-sul-numero-di-settembre-di-traveller-conde-nast-edizione-italiana\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.banfi.it\\\/castello-banfi-sul-numero-di-settembre-di-traveller-conde-nast-edizione-italiana\\\/\"},\"author\":{\"name\":\"Banfi Banfi\",\"@id\":\"https:\\\/\\\/www.banfi.it\\\/#\\\/schema\\\/person\\\/8a6a445b348dc073b2dee2e5ba75d2fa\"},\"headline\":\"Castello Banfi sul numero di settembre di Traveller, Cond\u00e9 Nast, edizione italiana\",\"datePublished\":\"2010-09-01T22:00:00+00:00\",\"dateModified\":\"2024-10-21T15:56:04+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.banfi.it\\\/castello-banfi-sul-numero-di-settembre-di-traveller-conde-nast-edizione-italiana\\\/\"},\"wordCount\":105,\"publisher\":{\"@id\":\"https:\\\/\\\/www.banfi.it\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.banfi.it\\\/castello-banfi-sul-numero-di-settembre-di-traveller-conde-nast-edizione-italiana\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.banfi.it\\\/wp-content\\\/uploads\\\/2010\\\/09\\\/banfi-castello-conde-nast-traveller-scaled.jpg\",\"articleSection\":[\"News\"],\"inLanguage\":\"en-GB\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.banfi.it\\\/castello-banfi-sul-numero-di-settembre-di-traveller-conde-nast-edizione-italiana\\\/\",\"url\":\"https:\\\/\\\/www.banfi.it\\\/castello-banfi-sul-numero-di-settembre-di-traveller-conde-nast-edizione-italiana\\\/\",\"name\":\"Castello Banfi sul numero di settembre di Traveller, Cond\u00e9 Nast, edizione italiana\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.banfi.it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.banfi.it\\\/castello-banfi-sul-numero-di-settembre-di-traveller-conde-nast-edizione-italiana\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.banfi.it\\\/castello-banfi-sul-numero-di-settembre-di-traveller-conde-nast-edizione-italiana\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.banfi.it\\\/wp-content\\\/uploads\\\/2010\\\/09\\\/banfi-castello-conde-nast-traveller-scaled.jpg\",\"datePublished\":\"2010-09-01T22:00:00+00:00\",\"dateModified\":\"2024-10-21T15:56:04+00:00\",\"description\":\"Castello Banfi sul numero di settembre di Traveller, Cond\u00e9 Nast, edizione italiana. Scopri di pi\u00f9 nell'articolo!\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.banfi.it\\\/castello-banfi-sul-numero-di-settembre-di-traveller-conde-nast-edizione-italiana\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.banfi.it\\\/castello-banfi-sul-numero-di-settembre-di-traveller-conde-nast-edizione-italiana\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/www.banfi.it\\\/castello-banfi-sul-numero-di-settembre-di-traveller-conde-nast-edizione-italiana\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.banfi.it\\\/wp-content\\\/uploads\\\/2010\\\/09\\\/banfi-castello-conde-nast-traveller-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/www.banfi.it\\\/wp-content\\\/uploads\\\/2010\\\/09\\\/banfi-castello-conde-nast-traveller-scaled.jpg\",\"width\":2560,\"height\":1707},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.banfi.it\\\/castello-banfi-sul-numero-di-settembre-di-traveller-conde-nast-edizione-italiana\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.banfi.it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"News\",\"item\":\"https:\\\/\\\/www.banfi.it\\\/category\\\/news\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Castello Banfi sul numero di settembre di Traveller, Cond\u00e9 Nast, edizione italiana\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.banfi.it\\\/#website\",\"url\":\"https:\\\/\\\/www.banfi.it\\\/\",\"name\":\"Banfi\",\"description\":\"For a better wine world\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.banfi.it\\\/#organization\"},\"alternateName\":\"Banfi\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.banfi.it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.banfi.it\\\/#organization\",\"name\":\"Banfi\",\"alternateName\":\"Banfi\",\"url\":\"https:\\\/\\\/www.banfi.it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/www.banfi.it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.banfi.it\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/Logo-stemma-banfi-scuro_a.png\",\"contentUrl\":\"https:\\\/\\\/www.banfi.it\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/Logo-stemma-banfi-scuro_a.png\",\"width\":186,\"height\":173,\"caption\":\"Banfi\"},\"image\":{\"@id\":\"https:\\\/\\\/www.banfi.it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/BanfiOfficial\",\"https:\\\/\\\/x.com\\\/BanfiOfficial\",\"https:\\\/\\\/www.instagram.com\\\/banfiofficial\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/banfiofficial\\\/\",\"https:\\\/\\\/www.youtube.com\\\/c\\\/Castellobanfi\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.banfi.it\\\/#\\\/schema\\\/person\\\/8a6a445b348dc073b2dee2e5ba75d2fa\",\"name\":\"Banfi Banfi\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0eeada89b82f4c563f9dc31d28d5b2ea9a9aaa487aaa4d39442ced8f921c6402?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0eeada89b82f4c563f9dc31d28d5b2ea9a9aaa487aaa4d39442ced8f921c6402?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0eeada89b82f4c563f9dc31d28d5b2ea9a9aaa487aaa4d39442ced8f921c6402?s=96&d=mm&r=g\",\"caption\":\"Banfi Banfi\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Castello Banfi in the September issue of Traveller, Cond\u00e9 Nast, Italian edition","description":"Castello Banfi in the September issue of Traveller, Cond\u00e9 Nast, Italian edition. Find out more in the article!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.banfi.it\/eng\/castello-banfi-in-the-september-issue-of-traveller-conde-nast-italian-edition\/","og_locale":"en_GB","og_type":"article","og_title":"Castello Banfi sul numero di settembre di Traveller, Cond\u00e9 Nast, edizione italiana","og_description":"Castello Banfi sul numero di settembre di Traveller, Cond\u00e9 Nast, edizione italiana. Scopri di pi\u00f9 nell'articolo!","og_url":"https:\/\/www.banfi.it\/eng\/castello-banfi-in-the-september-issue-of-traveller-conde-nast-italian-edition\/","og_site_name":"Banfi","article_publisher":"https:\/\/www.facebook.com\/BanfiOfficial","article_published_time":"2010-09-01T22:00:00+00:00","article_modified_time":"2024-10-21T15:56:04+00:00","og_image":[{"width":2560,"height":1707,"url":"https:\/\/www.banfi.it\/wp-content\/uploads\/2010\/09\/banfi-castello-conde-nast-traveller-scaled.jpg","type":"image\/jpeg"}],"author":"Banfi Banfi","twitter_card":"summary_large_image","twitter_creator":"@BanfiOfficial","twitter_site":"@BanfiOfficial","twitter_misc":{"Written by":"Banfi Banfi","Estimated reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.banfi.it\/castello-banfi-sul-numero-di-settembre-di-traveller-conde-nast-edizione-italiana\/#article","isPartOf":{"@id":"https:\/\/www.banfi.it\/castello-banfi-sul-numero-di-settembre-di-traveller-conde-nast-edizione-italiana\/"},"author":{"name":"Banfi Banfi","@id":"https:\/\/www.banfi.it\/#\/schema\/person\/8a6a445b348dc073b2dee2e5ba75d2fa"},"headline":"Castello Banfi sul numero di settembre di Traveller, Cond\u00e9 Nast, edizione italiana","datePublished":"2010-09-01T22:00:00+00:00","dateModified":"2024-10-21T15:56:04+00:00","mainEntityOfPage":{"@id":"https:\/\/www.banfi.it\/castello-banfi-sul-numero-di-settembre-di-traveller-conde-nast-edizione-italiana\/"},"wordCount":105,"publisher":{"@id":"https:\/\/www.banfi.it\/#organization"},"image":{"@id":"https:\/\/www.banfi.it\/castello-banfi-sul-numero-di-settembre-di-traveller-conde-nast-edizione-italiana\/#primaryimage"},"thumbnailUrl":"https:\/\/www.banfi.it\/wp-content\/uploads\/2010\/09\/banfi-castello-conde-nast-traveller-scaled.jpg","articleSection":["News"],"inLanguage":"en-GB"},{"@type":"WebPage","@id":"https:\/\/www.banfi.it\/castello-banfi-sul-numero-di-settembre-di-traveller-conde-nast-edizione-italiana\/","url":"https:\/\/www.banfi.it\/castello-banfi-sul-numero-di-settembre-di-traveller-conde-nast-edizione-italiana\/","name":"Castello Banfi in the September issue of Traveller, Cond\u00e9 Nast, Italian edition","isPartOf":{"@id":"https:\/\/www.banfi.it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.banfi.it\/castello-banfi-sul-numero-di-settembre-di-traveller-conde-nast-edizione-italiana\/#primaryimage"},"image":{"@id":"https:\/\/www.banfi.it\/castello-banfi-sul-numero-di-settembre-di-traveller-conde-nast-edizione-italiana\/#primaryimage"},"thumbnailUrl":"https:\/\/www.banfi.it\/wp-content\/uploads\/2010\/09\/banfi-castello-conde-nast-traveller-scaled.jpg","datePublished":"2010-09-01T22:00:00+00:00","dateModified":"2024-10-21T15:56:04+00:00","description":"Castello Banfi in the September issue of Traveller, Cond\u00e9 Nast, Italian edition. Find out more in the article!","breadcrumb":{"@id":"https:\/\/www.banfi.it\/castello-banfi-sul-numero-di-settembre-di-traveller-conde-nast-edizione-italiana\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.banfi.it\/castello-banfi-sul-numero-di-settembre-di-traveller-conde-nast-edizione-italiana\/"]}]},{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/www.banfi.it\/castello-banfi-sul-numero-di-settembre-di-traveller-conde-nast-edizione-italiana\/#primaryimage","url":"https:\/\/www.banfi.it\/wp-content\/uploads\/2010\/09\/banfi-castello-conde-nast-traveller-scaled.jpg","contentUrl":"https:\/\/www.banfi.it\/wp-content\/uploads\/2010\/09\/banfi-castello-conde-nast-traveller-scaled.jpg","width":2560,"height":1707},{"@type":"BreadcrumbList","@id":"https:\/\/www.banfi.it\/castello-banfi-sul-numero-di-settembre-di-traveller-conde-nast-edizione-italiana\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.banfi.it\/"},{"@type":"ListItem","position":2,"name":"News","item":"https:\/\/www.banfi.it\/category\/news\/"},{"@type":"ListItem","position":3,"name":"Castello Banfi sul numero di settembre di Traveller, Cond\u00e9 Nast, edizione italiana"}]},{"@type":"WebSite","@id":"https:\/\/www.banfi.it\/#website","url":"https:\/\/www.banfi.it\/","name":"Banfi","description":"For a better wine world","publisher":{"@id":"https:\/\/www.banfi.it\/#organization"},"alternateName":"Banfi","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.banfi.it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/www.banfi.it\/#organization","name":"Banfi","alternateName":"Banfi","url":"https:\/\/www.banfi.it\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/www.banfi.it\/#\/schema\/logo\/image\/","url":"https:\/\/www.banfi.it\/wp-content\/uploads\/2024\/06\/Logo-stemma-banfi-scuro_a.png","contentUrl":"https:\/\/www.banfi.it\/wp-content\/uploads\/2024\/06\/Logo-stemma-banfi-scuro_a.png","width":186,"height":173,"caption":"Banfi"},"image":{"@id":"https:\/\/www.banfi.it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/BanfiOfficial","https:\/\/x.com\/BanfiOfficial","https:\/\/www.instagram.com\/banfiofficial\/","https:\/\/www.linkedin.com\/company\/banfiofficial\/","https:\/\/www.youtube.com\/c\/Castellobanfi"]},{"@type":"Person","@id":"https:\/\/www.banfi.it\/#\/schema\/person\/8a6a445b348dc073b2dee2e5ba75d2fa","name":"Banfi Banfi","image":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/secure.gravatar.com\/avatar\/0eeada89b82f4c563f9dc31d28d5b2ea9a9aaa487aaa4d39442ced8f921c6402?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/0eeada89b82f4c563f9dc31d28d5b2ea9a9aaa487aaa4d39442ced8f921c6402?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/0eeada89b82f4c563f9dc31d28d5b2ea9a9aaa487aaa4d39442ced8f921c6402?s=96&d=mm&r=g","caption":"Banfi Banfi"}}]}},"_links":{"self":[{"href":"https:\/\/www.banfi.it\/eng\/wp-json\/wp\/v2\/posts\/13228","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.banfi.it\/eng\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.banfi.it\/eng\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.banfi.it\/eng\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/www.banfi.it\/eng\/wp-json\/wp\/v2\/comments?post=13228"}],"version-history":[{"count":0,"href":"https:\/\/www.banfi.it\/eng\/wp-json\/wp\/v2\/posts\/13228\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.banfi.it\/eng\/wp-json\/wp\/v2\/media\/16310"}],"wp:attachment":[{"href":"https:\/\/www.banfi.it\/eng\/wp-json\/wp\/v2\/media?parent=13228"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.banfi.it\/eng\/wp-json\/wp\/v2\/categories?post=13228"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.banfi.it\/eng\/wp-json\/wp\/v2\/tags?post=13228"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}